{"id":270,"count":1,"description":"","link":"https:\/\/drgoksel.com\/eng\/tag\/rhinoplasty-istanbul\/","name":"rhinoplasty Istanbul","slug":"rhinoplasty-istanbul","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>rhinoplasty Istanbul Archives - Op. Dr. Abd\u00fclkadir G\u00f6ksel - Nose Aesthetics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drgoksel.com\/eng\/tag\/rhinoplasty-istanbul\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"rhinoplasty Istanbul Archives - Op. Dr. Abd\u00fclkadir G\u00f6ksel - Nose Aesthetics\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drgoksel.com\/eng\/tag\/rhinoplasty-istanbul\/\" \/>\n<meta property=\"og:site_name\" content=\"Op. Dr. Abd\u00fclkadir G\u00f6ksel - Nose Aesthetics\" \/>\n<meta property=\"og:image\" content=\"https:\/\/drgoksel.com\/eng\/wp-content\/uploads\/2023\/01\/cropped-dr_abdulkadir_goksel-apple_logos-removebg-preview.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@akgoksel\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/drgoksel.com\/eng\/tag\/rhinoplasty-istanbul\/\",\"url\":\"https:\/\/drgoksel.com\/eng\/tag\/rhinoplasty-istanbul\/\",\"name\":\"rhinoplasty Istanbul Archives - Op. Dr. Abd\u00fclkadir G\u00f6ksel - Nose Aesthetics\",\"isPartOf\":{\"@id\":\"https:\/\/drgoksel.com\/eng\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/drgoksel.com\/eng\/tag\/rhinoplasty-istanbul\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/drgoksel.com\/eng\/tag\/rhinoplasty-istanbul\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/drgoksel.com\/eng\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"rhinoplasty Istanbul\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/drgoksel.com\/eng\/#website\",\"url\":\"https:\/\/drgoksel.com\/eng\/\",\"name\":\"Op. Dr. Abd\u00fclkadir G\u00f6ksel - Nose Aesthetics\",\"description\":\"Nose Aesthetics\",\"publisher\":{\"@id\":\"https:\/\/drgoksel.com\/eng\/#organization\"},\"alternateName\":\"Nose Aesthetics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/drgoksel.com\/eng\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/drgoksel.com\/eng\/#organization\",\"name\":\"Op. Dr. Abd\u00fclkadir G\u00f6ksel - Nose Aesthetics\",\"alternateName\":\"Rhinoplasty Surgeon in Istanbul Turkey\",\"url\":\"https:\/\/drgoksel.com\/eng\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/drgoksel.com\/eng\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/drgoksel.com\/eng\/wp-content\/uploads\/2023\/01\/cropped-dr_abdulkadir_goksel-apple_logos-removebg-preview.png\",\"contentUrl\":\"https:\/\/drgoksel.com\/eng\/wp-content\/uploads\/2023\/01\/cropped-dr_abdulkadir_goksel-apple_logos-removebg-preview.png\",\"width\":512,\"height\":512,\"caption\":\"Op. Dr. Abd\u00fclkadir G\u00f6ksel - Nose Aesthetics\"},\"image\":{\"@id\":\"https:\/\/drgoksel.com\/eng\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/www.facebook.com\/op.dr.a.Goksel\",\"https:\/\/x.com\/akgoksel\",\"https:\/\/instagram.com\/rinoistanbul\",\"https:\/\/www.youtube.com\/channel\/UCKkTC24CnqiZg8XIQ3yzUHQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"rhinoplasty Istanbul Archives - Op. Dr. Abd\u00fclkadir G\u00f6ksel - Nose Aesthetics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drgoksel.com\/eng\/tag\/rhinoplasty-istanbul\/","og_locale":"en_US","og_type":"article","og_title":"rhinoplasty Istanbul Archives - Op. Dr. Abd\u00fclkadir G\u00f6ksel - Nose Aesthetics","og_url":"https:\/\/drgoksel.com\/eng\/tag\/rhinoplasty-istanbul\/","og_site_name":"Op. Dr. Abd\u00fclkadir G\u00f6ksel - Nose Aesthetics","og_image":[{"width":512,"height":512,"url":"https:\/\/drgoksel.com\/eng\/wp-content\/uploads\/2023\/01\/cropped-dr_abdulkadir_goksel-apple_logos-removebg-preview.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@akgoksel","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/drgoksel.com\/eng\/tag\/rhinoplasty-istanbul\/","url":"https:\/\/drgoksel.com\/eng\/tag\/rhinoplasty-istanbul\/","name":"rhinoplasty Istanbul Archives - Op. Dr. Abd\u00fclkadir G\u00f6ksel - Nose Aesthetics","isPartOf":{"@id":"https:\/\/drgoksel.com\/eng\/#website"},"breadcrumb":{"@id":"https:\/\/drgoksel.com\/eng\/tag\/rhinoplasty-istanbul\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/drgoksel.com\/eng\/tag\/rhinoplasty-istanbul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/drgoksel.com\/eng\/"},{"@type":"ListItem","position":2,"name":"rhinoplasty Istanbul"}]},{"@type":"WebSite","@id":"https:\/\/drgoksel.com\/eng\/#website","url":"https:\/\/drgoksel.com\/eng\/","name":"Op. Dr. Abd\u00fclkadir G\u00f6ksel - Nose Aesthetics","description":"Nose Aesthetics","publisher":{"@id":"https:\/\/drgoksel.com\/eng\/#organization"},"alternateName":"Nose Aesthetics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drgoksel.com\/eng\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/drgoksel.com\/eng\/#organization","name":"Op. Dr. Abd\u00fclkadir G\u00f6ksel - Nose Aesthetics","alternateName":"Rhinoplasty Surgeon in Istanbul Turkey","url":"https:\/\/drgoksel.com\/eng\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/drgoksel.com\/eng\/#\/schema\/logo\/image\/","url":"https:\/\/drgoksel.com\/eng\/wp-content\/uploads\/2023\/01\/cropped-dr_abdulkadir_goksel-apple_logos-removebg-preview.png","contentUrl":"https:\/\/drgoksel.com\/eng\/wp-content\/uploads\/2023\/01\/cropped-dr_abdulkadir_goksel-apple_logos-removebg-preview.png","width":512,"height":512,"caption":"Op. Dr. Abd\u00fclkadir G\u00f6ksel - Nose Aesthetics"},"image":{"@id":"https:\/\/drgoksel.com\/eng\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/op.dr.a.Goksel","https:\/\/x.com\/akgoksel","https:\/\/instagram.com\/rinoistanbul","https:\/\/www.youtube.com\/channel\/UCKkTC24CnqiZg8XIQ3yzUHQ"]}]}},"_links":{"self":[{"href":"https:\/\/drgoksel.com\/eng\/wp-json\/wp\/v2\/tags\/270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drgoksel.com\/eng\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/drgoksel.com\/eng\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/drgoksel.com\/eng\/wp-json\/wp\/v2\/posts?tags=270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}